{"id":1533,"date":"2011-10-04T16:12:43","date_gmt":"2011-10-04T16:12:43","guid":{"rendered":"https:\/\/hannes-jaehnert.de\/wordpress\/?p=1533"},"modified":"2011-10-04T16:12:43","modified_gmt":"2011-10-04T16:12:43","slug":"zwei-thesen-zum-online-volunteering-im-osterreichischen-roten-kreuz","status":"publish","type":"post","link":"https:\/\/hannes-jaehnert.de\/wordpress\/2011\/10\/04\/zwei-thesen-zum-online-volunteering-im-osterreichischen-roten-kreuz\/","title":{"rendered":"Zwei Thesen zum Online-Volunteering im \u00d6sterreichischen Roten Kreuz"},"content":{"rendered":"<p>Es muss schon im Oktober letzen Jahres gewesen sein, als mich <a title=\"Redcrosssociologist Blog\" href=\"http:\/\/blog.roteskreuz.at\/sociologist\/\" target=\"_blank\" rel=\"noopener\">Gerald Czech<\/a> vom <a title=\"Kurzprofil von Gerald Czech auf www.rotkreuz.at\" href=\"http:\/\/www.roteskreuz.at\/kurse-aus-weiterbildung\/fuer-mitarbeiter\/bildungszentrum\/trainer-im-bz\/czech-gerald\/\" target=\"_blank\" rel=\"noopener\">\u00d6sterreichischen Roten Kreuz<\/a> fragte, ob ich nicht Lust h\u00e4tte, bei einer \u00d6RK-Konferenz in Krems an der Donau \u00fcber das Online-Volunteering zu sprechen. Nat\u00fcrlich sagte ich zu. Das \u00d6RK ist schlie\u00dflich eine jener vielversprechenden NPOs, die vielen anderen traditionellen Gro\u00dforganisationen im deutschen Sprachraum vormachen kann, dass die Freiwilligenarbeit \u00fcber das Internet auch f\u00fcr sie ein gangbarer Weg ist. Da Gerald und ich nun im Dezember <a title=\"Workshopank\u00fcndigung auf der Websteite des \u00d6RK Nieder\u00f6sterreich\" href=\"http:\/\/www.roteskreuz.at\/noe\/mitmachen\/freiwilligenkonferenz\/workshops\/online-volunteering\/\" target=\"_blank\" rel=\"noopener\">diesen Workshop zum Online-Volunteering<\/a> gemeinsam anbieten werden und das Thema \u201eneue Wege zur Freiwilligenarbeit\u201c u.E. die \u00d6ffentlichkeit bekommen sollte, die es verdient, entschieden wir, den Workshop im \u00f6ffentlichen Dialog \u00fcber unsere Weblogs vorzubereiten. Ich mache heute den Anfang und will hier zun\u00e4chst zwei Thesen formulieren, die den Nutzen des Online-Volunteerings f\u00fcr das \u00d6RK deutlich machen sollen. Nat\u00fcrlich kann sich jeder und jede einklinken \u2013 Erg\u00e4nzungen, Hinweise und Kritik sind uns immer willkommen.<\/p>\n<h1>Online-Volunteering: Eine Erg\u00e4nzung des Engagements \u201aon-site\u2018<\/h1>\n<p><a title=\"&quot;Wir haben die richtige Jacke f\u00fcr dich&quot;\" href=\"http:\/\/www.roteskreuz.at\/fileadmin\/user_upload\/LV\/Salzburg\/jacke_klein.gif\" target=\"_blank\" rel=\"noopener\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft\" title=\"Rotkreuz Jacke\" src=\"http:\/\/www.roteskreuz.at\/fileadmin\/user_upload\/LV\/Salzburg\/jacke_klein.gif\" alt=\"\" width=\"208\" height=\"437\" \/><\/a>Wer die <a href=\"http:\/\/www.roteskreuz.at\/noe\/mitmachen\/freiwilligenkonferenz\/\">Webseite zur Konferenz<\/a> besucht, bekommt zun\u00e4chst die Botschaft pr\u00e4sentiert, das \u00d6RK h\u00e4tte \u201edie richtige Jacke f\u00fcr dich\u201c. Pfiffige Freiwilligenwerbung w\u00fcrde ich sagen, doch trifft das auch auf mich zu? Hat das \u00d6RK auch Jacken f\u00fcr Ausl\u00e4nder, f\u00fcr nicht physisch pr\u00e4sente Sonderlinge, f\u00fcr Online- und Micro-Volunteers? Sicherlich nicht, f\u00fcr Online-Engagierte wird es k\u00fcnfitg eher Buttons f\u00fcr die Webseite geben, wie in der laufenden <a title=\"Facebook-Seite freiwillig 2011\" href=\"https:\/\/apps.facebook.com\/freiwillig\/\" target=\"_blank\" rel=\"noopener\">Facebook-Kampagne freiwillig 2011<\/a>. Das auf der Webseite aber mit dem symboltr\u00e4chtigen Kleidungsst\u00fcck geworben wird, spricht doch B\u00e4nde. Selbstverst\u00e4ndlich ist das Rote Kreuz auf physisch pr\u00e4sente Freiwillige angewiesen. Die Zeit, in der <a title=\"Micro-Volunteering and the Future - Part I\" href=\"http:\/\/dailycrowdsource.com\/2011\/07\/20\/lifestyle\/charity\/microvolunteering-and-the-future-part-i\/\" target=\"_blank\" rel=\"noopener\">Freiwillige Roboter \u00fcber das Netz steuern<\/a> werden, scheint mir (noch) in einer fernen und auch gar nicht so w\u00fcnschenswerten Zukunft zu liegen. Und doch gewinne ich den Eindruck, dass dem On-Site-Engagement hier gro\u00dfer Wert beigemessen und das Online-Engagement entsprechend untersch\u00e4tzt wird. Sicherlich kann das Online- und Micro-Volunteering den Rettungs- und Pflegedienst nicht ersetzen, Online- und Micro-Volunteers aber \u2013 das ist mein Vorschlag f\u00fcr die erste These \u2013 k\u00f6nnen die Arbeit \u201aam Menschen\u2018 sehr gut erg\u00e4nzen.<br \/>\nAus der Katastrophenhilfe dazu zwei Beispiele:<\/p>\n<ul>\n<li>Ein erstes Beispiel f\u00fcr die Unterst\u00fctzung der Katastrophenhilfe vor Ort, lieferte Anfang 2010 das US-amerikanische StartUp <a title=\"www.spaked.com\" href=\"http:\/\/www.sparked.com\/\" target=\"_blank\" rel=\"noopener\">\u201eThe Extraordinaries\u201c<\/a>. Nach dem katastrophalen Erdbeben im Januar 2010 auf Haiti setzen die Extraordinaries ein System auf, mit dem vermisste Personen ausfindig gemacht werden konnten. Daf\u00fcr wurde die digitale Bilderflut aus dem haitianischen Katastrophengebiet zun\u00e4chst mittels Schlagworten (bspw. \u201eM\u00e4dchen\u201c, \u201eJunge\u201c, \u201ealte Frau\u201c) kategorisiert und anschlie\u00dfend zusammen mit eventuell passenden Bildern von Vermissten (eben Jungen, M\u00e4dchen und alten Frauen) \u00fcber eine iPhone-App angezeigt. Der Engagement-Task beschr\u00e4nkte sich dann nur noch auf das vergleichen zweier Bilder und das dr\u00fccken eines von zwei Kn\u00f6pfen: passt oder passt nicht. Die Zahl der so ausfindig gemachten Personen mag angesichts der Not tausender mit 24 recht mickrig scheinen, doch wer will schon sagen, dass es den Aufwand nicht Wert gewesen w\u00e4re?<\/li>\n<li>Ein zweites Beispiel f\u00fcr die Unterst\u00fctzung der humanit\u00e4ren Hilfe durch Online-Volunteers bietet zweifelsohne die Mapping-Plattform <a title=\"www.ushahidi.com\" href=\"http:\/\/www.ushahidi.com\/\" target=\"_blank\" rel=\"noopener\">Ushahidi<\/a>. Via SMS, MMS oder Online-Applikation werden auf den Karten von Ushahidi Krisengebiete und Konfliktherde in der ganzen Welt markiert und mit zur Verf\u00fcgung stehenden Informationen versehen. Sicherlich lassen sich schon diejenigen, die die diversen Informationen auf den Karten von Ushahidi einpflegen als Micro-Volunteers bezeichnen, ohne das Engagement der vielen engagierten Webentwickler und Programmiererinnen aber w\u00e4re ein Crowdsourcing dieses Umfangs nicht m\u00f6glich. Konnten sich f\u00fcr die Vermisstensuche der Extraordinaries nur Freiwilligen mit einem iPhone engagieren, ist Ushahidi mit beinahe allem kompatibel, was Daten senden kann.<\/li>\n<\/ul>\n<p>Nat\u00fcrlich gibt es noch weiter Beispiele f\u00fcr wirkungsm\u00e4chtige Freiwilligenarbeit \u00fcber das Internet. Die beiden genannten sollten an dieser Stelle aber ausreichen, um einen \u00dcbertrag auf die praktische Arbeit des \u00d6sterreichischen Roten Kreuzes zu wagen. Beide Beispiele zeigen schlie\u00dflich, dass Online-Volunteers von zu Hause, vom Arbeitsrechner oder von unterwegs aus die Arbeit der freiwillig und hauptamtlich Mitarbeitenden vor Ort wirksam unterst\u00fctzen k\u00f6nnen. Einerseits k\u00f6nnen sie Informationen recherchieren und \u00fcber Webapplikationen zur Verf\u00fcgung stellen, andererseits k\u00f6nnen sie eben diese Webapplikationen selbst (mit) gestalten und\/oder programmieren. Wenn ich recht informiert bin, hat es diesbez\u00fcglich auch schon erste erfolgreiche Ans\u00e4tze im \u00d6RK gegeben. (<a title=\"Engagementangebot auf Twitter\" href=\"http:\/\/twitter.com\/#%21\/redcrosswebmast\/status\/43671252224839681\" target=\"_blank\" rel=\"noopener\">Twitter<\/a> | <a title=\"Engagementangebot auf Facebook\" href=\"https:\/\/www.facebook.com\/roteskreuzat\/posts\/10150550494840557\" target=\"_blank\" rel=\"noopener\">Facebook<\/a>)<br \/>\nDie wirksame Unterst\u00fctzung durch Volunteers, die sich \u00fcberwiegend \u00fcber das Internet einbringen, muss dabei nat\u00fcrlich nicht nur auf die Katastrophenhilfe beschr\u00e4nkt bleiben. Wie der Erfolg des <a title=\"Team \u00d6sterreich - Informationen auf rotkreuz.at\" href=\"http:\/\/www.roteskreuz.at\/wien\/mitmachen\/mitarbeit\/freiwillige-mitarbeit\/team-oesterreich\/\" target=\"_blank\" rel=\"noopener\">\u201eTeam \u00d6sterreich\u201c<\/a> zeigt, gibt es hier zwar gro\u00dfes Potential, doch ist der Einbezug auch in anderen Bereichen der Rotkreuzarbeit sinnvoll. Vorstellbar sind z.B. Online-Mentoring-Programme mit \u00e4lteren und j\u00fcngeren Beteiligten, kollaborative Wissenssammlungen und -recherche sowie \u201eKlickarbeit\u201c bei Testl\u00e4ufen von Webapplikationen \u2026*<\/p>\n<h1>Online-Volunteering: Hierarchiearme Beziehungspflege f\u00fcr NPOs<\/h1>\n<p>Im Zuge meines <a title=\"&quot;Suche Online-Volunteers Part I&quot; Beitrag hier im Blog\" href=\"https:\/\/hannes-jaehnert.de\/2011\/03\/07\/%E2%80%9Esuche-online-volunteers%E2%80%9C-engagementangebote-auf-facebook-im-vergleich\/\" target=\"_blank\" rel=\"noopener\">Vergleiches der Online-Engagementangebote<\/a>, die das \u00d6sterreichische Rote Kreuz und <a title=\"Webseite von 2aid.org\" href=\"http:\/\/www.2aid.org\/\" target=\"_blank\" rel=\"noopener\">2aid.org<\/a> auf Facebook einstellten, vermutete ich, dass das Engagementangebot des \u00d6RK vor allem einen strategischer Einbezug der Facebook-Fans als aktive Mitgestalterinnen und Mitgestalter darstellte. Zwar kommentierte Gerald, dass das Engagement der freiwilligen \u00dcbersetzerinnen und \u00dcbersetzer durchaus auch kompensatorischen Charakter hatte, doch bezweifle ich, dass darin die gro\u00dfe St\u00e4rke dieser Art des Einbezugs lag. Einerseits wurde mit der Suche nach \u201evirtuellen Freiwilligen\u201c einiges an Aktivit\u00e4t provoziert, was f\u00fcr den Betrieb von Facebook-Seiten niemals schlecht ist, andererseits zeigt ein Blick in die Infos zu den Kommentatorinnen und Kommentatoren, dass diese aus allen Ecken der Alpen (nicht nur aus \u00d6sterreich) stammten. Mit ihrem Online-Engagement f\u00fcr den Dachverband des \u00d6sterreichischen Roten Kreuzes \u2013 so meine n\u00e4chste These f\u00fcr unseren Workshop im Dezember \u2013 wurde also die Beziehung zu einem eher abstrakten Gebilde intensiviert.<br \/>\nDas Engagement der etwa 51.000 Freiwilligen des \u00d6sterreichischen Roten Kreuzes wird f\u00f6deral organisiert. Es gibt 10 Landesverb\u00e4nde mit jeweils mehreren Bezirksstellen, die alle einem Dach- oder Bundesverband untergeordnet sind. Das hat den Vorteil, dass der lokale Bezirksverband f\u00fcr Engagierte durchaus greifbar ist. Die Ansprechpartnerinnen und -partner sind hier (bestenfalls) wohlbekannt. Interessierte k\u00f6nnen das jeweilige B\u00fcro der Freiwilligenkoordination besuchen, sich informieren oder vielleicht auch kritische Fragen diskutieren. Beim Landesverband (eine Ebene dar\u00fcber) ist das schon schwieriger. Hier d\u00fcrfte es eher um die strukturellen Rahmenbedingungen der Freiwilligenarbeit und die Lobbyarbeit gehen. Sicherlich ist freiwilliges Engagement auch hier noch m\u00f6glich, doch das Retten, Bergen und Pflegen muss man sich an dieser Stelle schon dazu denken. Im Bundesverband (noch eine Ebene h\u00f6her) schlie\u00dflich geht es um grunds\u00e4tzliche Fragen der Imagepflege und des Marketing, der Ressourcenbeschaffung und der (internationalen) Netzwerkarbeit, was den Einbezug freiwilligen Engagements noch schwieriger erscheinen l\u00e4sst. Je h\u00f6her also die Eben dieses hierarchischen Systems, desto abstrakter die Arbeit, die dort geleistet wird und desto weniger hat die Freiwilligenarbeit dort (wenn sie \u00fcberhaupt m\u00f6glich ist) noch etwas mit dem zu tun, was weithin mit dem Roten Kreuz in Verbindung gebracht wird. Und dennoch macht die Erm\u00f6glichung des Online-Engagements auf allen Ebenen Sinn:<\/p>\n<ol>\n<li>Auf der lokalen Ebene macht die Online-Beteiligung Freiwilliger Sinn, weil sich so <em>auch<\/em> Menschen in die (notwendige) <a title=\"Beitrag zur Koproduktion sozialer Dienstleistungen von Brigitte Reiser\" href=\"http:\/\/blog.nonprofits-vernetzt.de\/index.php\/die-koproduktion-von-dienstleistungen-wie-konnen-profis-und-burger-zusammenarbeiten\/\" target=\"_blank\" rel=\"noopener\">Koproduktion sozialer Dienstleistungen<\/a> einbringen k\u00f6nnen, die ihr zu Hause oder ihren Arbeitsplatz nicht ohne Weiteres verlassen k\u00f6nnen. Gemeint sind hier nicht nur Menschen mit Behinderung, die wie alle anderen auch ein Recht auf Partizipation haben. Gemeint sind hier auch Frauen und M\u00e4nner mit kleinen Kindern oder pflegebed\u00fcrftigen Angeh\u00f6rigen. Mit dem Ansatz der Koproduktion k\u00f6nnen Hierarchien zwischen den Leistungsempf\u00e4ngern und -erbringern \u2013 seien es nun Freiwillige oder Hauptamtliche \u2013 abgebaut werden, weil die Leistungserbringung so gestaltet wird, dass alle Seiten damit einverstanden sind und sich niemand als eine Art \u201aAbnehmer wider Willen\u2018 sehen muss.<\/li>\n<li>Sicherlich sind solcherlei Koproduktionsans\u00e4tze auch auf Landesebene denkbar, des h\u00f6heren Abstraktionsgrades wegen aber schwieriger umzusetzen. Da es hier eher um die strukturellen Rahmenbedingungen und die Einflussnahme auf politische Prozesse im Land geht, ist das freiwillige Online-Engagement hier vor allem bei der kollaborativen Erarbeitung von Konzepten und Papieren denkbar. Und auch dieses etwas trockene Engagement w\u00fcrde (a) die Hierarchie zwischen Landesverband und freiwilligen Unterst\u00fctzerinnen und Unterst\u00fctzer abbauen helfen und (b) auch einiges an Mobilisierungspotential (bspw. f\u00fcr politische Aktionen) beim Landesverband b\u00fcndeln.<\/li>\n<li>Auf der drittgenannten Ebene, der des Bundesverbandes, vermag ich schlie\u00dflich nur gelegentliche Ansatzpunkte f\u00fcr die Koproduktion zu erkennen. Einer davon war nat\u00fcrlich die <a title=\"Social Media Policy des \u00d6RK im Wiki\" href=\"http:\/\/blog.roteskreuz.at\/wiki\/index.php\/Social_Media_Policy\" target=\"_blank\" rel=\"noopener\">gemeinschaftliche Erarbeitung<\/a> der <a title=\"Verabschiedete Social Media Policy (PDF)\" href=\"http:\/\/www.roteskreuz.at\/fileadmin\/user_upload\/PDF\/Was_wir_tun\/Social-Media-Policy.pdf\" target=\"_blank\" rel=\"noopener\">Social Media Policy des \u00d6sterreichischen Roten Kreuzes<\/a>, bei der sich vielerlei Akteure einbrachten, die mithin auch nicht zum \u00d6RK geh\u00f6rten. Vielleicht lassen sich auf diesem Wege auch Tool-Kits nach dem Vorbild von <a title=\"Webseite www.greenaction.de \" href=\"http:\/\/www.greenaction.de\/\" target=\"_blank\" rel=\"noopener\">Green Action<\/a> erstellen, doch reicht meine Phantasie dar\u00fcber hinaus nicht mehr weiter.* Das Online-Volunteering sehe ich auf dieser Ebene vor allem als eine M\u00f6glichkeit aktive Unterst\u00fctzung m\u00f6glich zu machen und den Dachverband via Social Media ein St\u00fcck n\u00e4her an die Lebenswirklichkeit seiner Stakeholder zu r\u00fccken.<\/li>\n<\/ol>\n<p>Vielleicht sind meine hier formulierten Vorstellungen von der f\u00f6deralen Struktur des \u00d6RK und den Aufgaben der jeweiligen Verbandsebenen nicht an allen Stellen richtig. Ich hoffe Gerald wird \u2013 wenn n\u00f6tig \u2013 Licht ins Dunkel bringen, denn ich glaube, dass die Freiwilligenarbeit (online oder on-site) und die organisationale Struktur in einer Wechselwirkung zueinander stehen, der mit Bedacht begegnet werden muss. Freiwilligenmanagement meint nicht die blo\u00dfe Verwaltung des Ehrenamts, sondern auch die stete Organisationsentwicklung, die die Kenntnis der jeweiligen Strukturen voraussetzt.<br \/>\n*<em>F\u00fcr die Diskussion in Workshops und Seminaren haben kreative Vorschl\u00e4ge gro\u00dfen Wert. Einige Vorschl\u00e4ge habe ich hier schon formuliert, einige wurden bereits auf der <a title=\"Frage auf Facebook zu vorstellbaren Online-Engagements\" href=\"https:\/\/www.facebook.com\/roteskreuzat\/posts\/10150550494840557\" target=\"_blank\" rel=\"noopener\">Facebook-Seite des \u00d6RK eingebracht<\/a>. Wenn du auf die Schnelle allerdings eine Idee hast, wie sich Freiwillige auf Bundes-, Landes- und kommunaler Ebene\u00a0 einbringen k\u00f6nnten, schreib sie doch einfach in die Kommentare unter diesem Beitrag. Vielen Dank.<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Es muss schon im Oktober letzen Jahres gewesen sein, als mich Gerald Czech vom \u00d6sterreichischen Roten Kreuz fragte, ob ich nicht Lust h\u00e4tte, bei einer \u00d6RK-Konferenz in Krems an der Donau \u00fcber das Online-Volunteering zu sprechen. Nat\u00fcrlich sagte ich zu. Das \u00d6RK ist schlie\u00dflich eine jener vielversprechenden NPOs, die vielen anderen traditionellen Gro\u00dforganisationen im deutschen [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[27,37],"tags":[65,329,159],"class_list":["post-1533","post","type-post","status-publish","format-standard","hentry","category-blog","category-online-freiwilligenarbeit","tag-online-volunteering","tag-ork","tag-workshop"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.7 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Zwei Thesen zum Online-Volunteering im \u00d6sterreichischen Roten Kreuz &#8902; Hannes J\u00e4hnert<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/hannes-jaehnert.de\/wordpress\/2011\/10\/04\/zwei-thesen-zum-online-volunteering-im-osterreichischen-roten-kreuz\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Zwei Thesen zum Online-Volunteering im \u00d6sterreichischen Roten Kreuz &#8902; Hannes J\u00e4hnert\" \/>\n<meta property=\"og:description\" content=\"Es muss schon im Oktober letzen Jahres gewesen sein, als mich Gerald Czech vom \u00d6sterreichischen Roten Kreuz fragte, ob ich nicht Lust h\u00e4tte, bei einer \u00d6RK-Konferenz in Krems an der Donau \u00fcber das Online-Volunteering zu sprechen. Nat\u00fcrlich sagte ich zu. Das \u00d6RK ist schlie\u00dflich eine jener vielversprechenden NPOs, die vielen anderen traditionellen Gro\u00dforganisationen im deutschen [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/hannes-jaehnert.de\/wordpress\/2011\/10\/04\/zwei-thesen-zum-online-volunteering-im-osterreichischen-roten-kreuz\/\" \/>\n<meta property=\"og:site_name\" content=\"Hannes J\u00e4hnert\" \/>\n<meta property=\"article:published_time\" content=\"2011-10-04T16:12:43+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/www.roteskreuz.at\/fileadmin\/user_upload\/LV\/Salzburg\/jacke_klein.gif\" \/>\n<meta name=\"author\" content=\"foulder\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"foulder\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"8\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/hannes-jaehnert.de\\\/wordpress\\\/2011\\\/10\\\/04\\\/zwei-thesen-zum-online-volunteering-im-osterreichischen-roten-kreuz\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/hannes-jaehnert.de\\\/wordpress\\\/2011\\\/10\\\/04\\\/zwei-thesen-zum-online-volunteering-im-osterreichischen-roten-kreuz\\\/\"},\"author\":{\"name\":\"foulder\",\"@id\":\"https:\\\/\\\/hannes-jaehnert.de\\\/wordpress\\\/#\\\/schema\\\/person\\\/1ab60f3bc0cd8e11ede09e5dc21d43b5\"},\"headline\":\"Zwei Thesen zum Online-Volunteering im \u00d6sterreichischen Roten Kreuz\",\"datePublished\":\"2011-10-04T16:12:43+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/hannes-jaehnert.de\\\/wordpress\\\/2011\\\/10\\\/04\\\/zwei-thesen-zum-online-volunteering-im-osterreichischen-roten-kreuz\\\/\"},\"wordCount\":1628,\"commentCount\":5,\"publisher\":{\"@id\":\"https:\\\/\\\/hannes-jaehnert.de\\\/wordpress\\\/#\\\/schema\\\/person\\\/1ab60f3bc0cd8e11ede09e5dc21d43b5\"},\"image\":{\"@id\":\"https:\\\/\\\/hannes-jaehnert.de\\\/wordpress\\\/2011\\\/10\\\/04\\\/zwei-thesen-zum-online-volunteering-im-osterreichischen-roten-kreuz\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/www.roteskreuz.at\\\/fileadmin\\\/user_upload\\\/LV\\\/Salzburg\\\/jacke_klein.gif\",\"keywords\":[\"Online-Volunteering\",\"\u00d6RK\",\"Workshop\"],\"articleSection\":[\"Blog\",\"Online-Freiwilligenarbeit\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/hannes-jaehnert.de\\\/wordpress\\\/2011\\\/10\\\/04\\\/zwei-thesen-zum-online-volunteering-im-osterreichischen-roten-kreuz\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/hannes-jaehnert.de\\\/wordpress\\\/2011\\\/10\\\/04\\\/zwei-thesen-zum-online-volunteering-im-osterreichischen-roten-kreuz\\\/\",\"url\":\"https:\\\/\\\/hannes-jaehnert.de\\\/wordpress\\\/2011\\\/10\\\/04\\\/zwei-thesen-zum-online-volunteering-im-osterreichischen-roten-kreuz\\\/\",\"name\":\"Zwei Thesen zum Online-Volunteering im \u00d6sterreichischen Roten Kreuz &#8902; Hannes J\u00e4hnert\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/hannes-jaehnert.de\\\/wordpress\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/hannes-jaehnert.de\\\/wordpress\\\/2011\\\/10\\\/04\\\/zwei-thesen-zum-online-volunteering-im-osterreichischen-roten-kreuz\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/hannes-jaehnert.de\\\/wordpress\\\/2011\\\/10\\\/04\\\/zwei-thesen-zum-online-volunteering-im-osterreichischen-roten-kreuz\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/www.roteskreuz.at\\\/fileadmin\\\/user_upload\\\/LV\\\/Salzburg\\\/jacke_klein.gif\",\"datePublished\":\"2011-10-04T16:12:43+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/hannes-jaehnert.de\\\/wordpress\\\/2011\\\/10\\\/04\\\/zwei-thesen-zum-online-volunteering-im-osterreichischen-roten-kreuz\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/hannes-jaehnert.de\\\/wordpress\\\/2011\\\/10\\\/04\\\/zwei-thesen-zum-online-volunteering-im-osterreichischen-roten-kreuz\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/hannes-jaehnert.de\\\/wordpress\\\/2011\\\/10\\\/04\\\/zwei-thesen-zum-online-volunteering-im-osterreichischen-roten-kreuz\\\/#primaryimage\",\"url\":\"http:\\\/\\\/www.roteskreuz.at\\\/fileadmin\\\/user_upload\\\/LV\\\/Salzburg\\\/jacke_klein.gif\",\"contentUrl\":\"http:\\\/\\\/www.roteskreuz.at\\\/fileadmin\\\/user_upload\\\/LV\\\/Salzburg\\\/jacke_klein.gif\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/hannes-jaehnert.de\\\/wordpress\\\/2011\\\/10\\\/04\\\/zwei-thesen-zum-online-volunteering-im-osterreichischen-roten-kreuz\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/hannes-jaehnert.de\\\/wordpress\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Zwei Thesen zum Online-Volunteering im \u00d6sterreichischen Roten Kreuz\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/hannes-jaehnert.de\\\/wordpress\\\/#website\",\"url\":\"https:\\\/\\\/hannes-jaehnert.de\\\/wordpress\\\/\",\"name\":\"Hannes J\u00e4hnert\",\"description\":\"Engagementblogger &amp; Freizeitforscher\",\"publisher\":{\"@id\":\"https:\\\/\\\/hannes-jaehnert.de\\\/wordpress\\\/#\\\/schema\\\/person\\\/1ab60f3bc0cd8e11ede09e5dc21d43b5\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/hannes-jaehnert.de\\\/wordpress\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/hannes-jaehnert.de\\\/wordpress\\\/#\\\/schema\\\/person\\\/1ab60f3bc0cd8e11ede09e5dc21d43b5\",\"name\":\"foulder\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/hannes-jaehnert.de\\\/wordpress\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/hannes-jaehnert_gemacht.jpg\",\"url\":\"https:\\\/\\\/hannes-jaehnert.de\\\/wordpress\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/hannes-jaehnert_gemacht.jpg\",\"contentUrl\":\"https:\\\/\\\/hannes-jaehnert.de\\\/wordpress\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/hannes-jaehnert_gemacht.jpg\",\"width\":2000,\"height\":2000,\"caption\":\"foulder\"},\"logo\":{\"@id\":\"https:\\\/\\\/hannes-jaehnert.de\\\/wordpress\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/hannes-jaehnert_gemacht.jpg\"},\"url\":\"https:\\\/\\\/hannes-jaehnert.de\\\/wordpress\\\/author\\\/foulder\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Zwei Thesen zum Online-Volunteering im \u00d6sterreichischen Roten Kreuz &#8902; Hannes J\u00e4hnert","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/hannes-jaehnert.de\/wordpress\/2011\/10\/04\/zwei-thesen-zum-online-volunteering-im-osterreichischen-roten-kreuz\/","og_locale":"de_DE","og_type":"article","og_title":"Zwei Thesen zum Online-Volunteering im \u00d6sterreichischen Roten Kreuz &#8902; Hannes J\u00e4hnert","og_description":"Es muss schon im Oktober letzen Jahres gewesen sein, als mich Gerald Czech vom \u00d6sterreichischen Roten Kreuz fragte, ob ich nicht Lust h\u00e4tte, bei einer \u00d6RK-Konferenz in Krems an der Donau \u00fcber das Online-Volunteering zu sprechen. Nat\u00fcrlich sagte ich zu. Das \u00d6RK ist schlie\u00dflich eine jener vielversprechenden NPOs, die vielen anderen traditionellen Gro\u00dforganisationen im deutschen [&hellip;]","og_url":"https:\/\/hannes-jaehnert.de\/wordpress\/2011\/10\/04\/zwei-thesen-zum-online-volunteering-im-osterreichischen-roten-kreuz\/","og_site_name":"Hannes J\u00e4hnert","article_published_time":"2011-10-04T16:12:43+00:00","og_image":[{"url":"http:\/\/www.roteskreuz.at\/fileadmin\/user_upload\/LV\/Salzburg\/jacke_klein.gif","type":"","width":"","height":""}],"author":"foulder","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"foulder","Gesch\u00e4tzte Lesezeit":"8\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/hannes-jaehnert.de\/wordpress\/2011\/10\/04\/zwei-thesen-zum-online-volunteering-im-osterreichischen-roten-kreuz\/#article","isPartOf":{"@id":"https:\/\/hannes-jaehnert.de\/wordpress\/2011\/10\/04\/zwei-thesen-zum-online-volunteering-im-osterreichischen-roten-kreuz\/"},"author":{"name":"foulder","@id":"https:\/\/hannes-jaehnert.de\/wordpress\/#\/schema\/person\/1ab60f3bc0cd8e11ede09e5dc21d43b5"},"headline":"Zwei Thesen zum Online-Volunteering im \u00d6sterreichischen Roten Kreuz","datePublished":"2011-10-04T16:12:43+00:00","mainEntityOfPage":{"@id":"https:\/\/hannes-jaehnert.de\/wordpress\/2011\/10\/04\/zwei-thesen-zum-online-volunteering-im-osterreichischen-roten-kreuz\/"},"wordCount":1628,"commentCount":5,"publisher":{"@id":"https:\/\/hannes-jaehnert.de\/wordpress\/#\/schema\/person\/1ab60f3bc0cd8e11ede09e5dc21d43b5"},"image":{"@id":"https:\/\/hannes-jaehnert.de\/wordpress\/2011\/10\/04\/zwei-thesen-zum-online-volunteering-im-osterreichischen-roten-kreuz\/#primaryimage"},"thumbnailUrl":"http:\/\/www.roteskreuz.at\/fileadmin\/user_upload\/LV\/Salzburg\/jacke_klein.gif","keywords":["Online-Volunteering","\u00d6RK","Workshop"],"articleSection":["Blog","Online-Freiwilligenarbeit"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/hannes-jaehnert.de\/wordpress\/2011\/10\/04\/zwei-thesen-zum-online-volunteering-im-osterreichischen-roten-kreuz\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/hannes-jaehnert.de\/wordpress\/2011\/10\/04\/zwei-thesen-zum-online-volunteering-im-osterreichischen-roten-kreuz\/","url":"https:\/\/hannes-jaehnert.de\/wordpress\/2011\/10\/04\/zwei-thesen-zum-online-volunteering-im-osterreichischen-roten-kreuz\/","name":"Zwei Thesen zum Online-Volunteering im \u00d6sterreichischen Roten Kreuz &#8902; Hannes J\u00e4hnert","isPartOf":{"@id":"https:\/\/hannes-jaehnert.de\/wordpress\/#website"},"primaryImageOfPage":{"@id":"https:\/\/hannes-jaehnert.de\/wordpress\/2011\/10\/04\/zwei-thesen-zum-online-volunteering-im-osterreichischen-roten-kreuz\/#primaryimage"},"image":{"@id":"https:\/\/hannes-jaehnert.de\/wordpress\/2011\/10\/04\/zwei-thesen-zum-online-volunteering-im-osterreichischen-roten-kreuz\/#primaryimage"},"thumbnailUrl":"http:\/\/www.roteskreuz.at\/fileadmin\/user_upload\/LV\/Salzburg\/jacke_klein.gif","datePublished":"2011-10-04T16:12:43+00:00","breadcrumb":{"@id":"https:\/\/hannes-jaehnert.de\/wordpress\/2011\/10\/04\/zwei-thesen-zum-online-volunteering-im-osterreichischen-roten-kreuz\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/hannes-jaehnert.de\/wordpress\/2011\/10\/04\/zwei-thesen-zum-online-volunteering-im-osterreichischen-roten-kreuz\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/hannes-jaehnert.de\/wordpress\/2011\/10\/04\/zwei-thesen-zum-online-volunteering-im-osterreichischen-roten-kreuz\/#primaryimage","url":"http:\/\/www.roteskreuz.at\/fileadmin\/user_upload\/LV\/Salzburg\/jacke_klein.gif","contentUrl":"http:\/\/www.roteskreuz.at\/fileadmin\/user_upload\/LV\/Salzburg\/jacke_klein.gif"},{"@type":"BreadcrumbList","@id":"https:\/\/hannes-jaehnert.de\/wordpress\/2011\/10\/04\/zwei-thesen-zum-online-volunteering-im-osterreichischen-roten-kreuz\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/hannes-jaehnert.de\/wordpress\/"},{"@type":"ListItem","position":2,"name":"Zwei Thesen zum Online-Volunteering im \u00d6sterreichischen Roten Kreuz"}]},{"@type":"WebSite","@id":"https:\/\/hannes-jaehnert.de\/wordpress\/#website","url":"https:\/\/hannes-jaehnert.de\/wordpress\/","name":"Hannes J\u00e4hnert","description":"Engagementblogger &amp; Freizeitforscher","publisher":{"@id":"https:\/\/hannes-jaehnert.de\/wordpress\/#\/schema\/person\/1ab60f3bc0cd8e11ede09e5dc21d43b5"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/hannes-jaehnert.de\/wordpress\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":["Person","Organization"],"@id":"https:\/\/hannes-jaehnert.de\/wordpress\/#\/schema\/person\/1ab60f3bc0cd8e11ede09e5dc21d43b5","name":"foulder","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/hannes-jaehnert.de\/wordpress\/wp-content\/uploads\/2021\/02\/hannes-jaehnert_gemacht.jpg","url":"https:\/\/hannes-jaehnert.de\/wordpress\/wp-content\/uploads\/2021\/02\/hannes-jaehnert_gemacht.jpg","contentUrl":"https:\/\/hannes-jaehnert.de\/wordpress\/wp-content\/uploads\/2021\/02\/hannes-jaehnert_gemacht.jpg","width":2000,"height":2000,"caption":"foulder"},"logo":{"@id":"https:\/\/hannes-jaehnert.de\/wordpress\/wp-content\/uploads\/2021\/02\/hannes-jaehnert_gemacht.jpg"},"url":"https:\/\/hannes-jaehnert.de\/wordpress\/author\/foulder\/"}]}},"views":1634,"_links":{"self":[{"href":"https:\/\/hannes-jaehnert.de\/wordpress\/wp-json\/wp\/v2\/posts\/1533","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hannes-jaehnert.de\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/hannes-jaehnert.de\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/hannes-jaehnert.de\/wordpress\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/hannes-jaehnert.de\/wordpress\/wp-json\/wp\/v2\/comments?post=1533"}],"version-history":[{"count":0,"href":"https:\/\/hannes-jaehnert.de\/wordpress\/wp-json\/wp\/v2\/posts\/1533\/revisions"}],"wp:attachment":[{"href":"https:\/\/hannes-jaehnert.de\/wordpress\/wp-json\/wp\/v2\/media?parent=1533"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/hannes-jaehnert.de\/wordpress\/wp-json\/wp\/v2\/categories?post=1533"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/hannes-jaehnert.de\/wordpress\/wp-json\/wp\/v2\/tags?post=1533"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}