{"id":27,"date":"2008-11-12T18:23:00","date_gmt":"2008-11-12T18:23:00","guid":{"rendered":"http:\/\/foulder.wordpress.com\/2008\/11\/12\/zusammenfassung-der-arbeit-als-externer-betreuer"},"modified":"2008-11-12T18:23:00","modified_gmt":"2008-11-12T18:23:00","slug":"zusammenfassung-der-arbeit-als-externer-betreuer","status":"publish","type":"post","link":"https:\/\/hannes-jaehnert.de\/wordpress\/2008\/11\/12\/zusammenfassung-der-arbeit-als-externer-betreuer\/","title":{"rendered":"Zusammenfassung der Arbeit als Externer Betreuer"},"content":{"rendered":"<p><span style=\"font-family:verdana;\">Nun: Ich denke die erste Mission, mal nieder zu schreiben, wie das so l\u00e4uft mit der Betreuung einer Seminarfacharbeit, habe ich erf\u00fcllt. Hier eine kurze Zusammenfassung:<\/span><br \/><span style=\"font-family:verdana;\">(1) Die externe Betreuung einer Seminarfacharbeit, Projektarbeit oder wie immer es genannt wird ist eine Angelegenheit b\u00fcrgerschaftlichen Engagements.<\/span><br \/><span style=\"font-family:verdana;\">(2) Man m\u00f6ge diesem Job nicht hinterher rennen, er kann hin und wieder frustrieren &#8230; <\/span><br \/><span style=\"font-family:verdana;\">(3) Die Kontaktaufnahme mit der Schule gestaltet sich manchmal kompliziert. Es ist sinnvoll die Schule w\u00e4hrend der Schulzeit [!] zu besuchen oder &#8212; wenn das nicht m\u00f6glich ist &#8212; seine Telefonnummer hinterlassen. Den Lehrer oder die Lehrerin erreicht man sowieso nur mit viel Gl\u00fcck. <\/span><br \/><span style=\"font-family:verdana;\">(4) Die Aufgaben eines &#8220;Externen&#8221; sind folgende<\/span><br \/><span style=\"font-family:verdana;\">&#8211; <\/span><span style=\"font-family:verdana;\">Das Seminarfachteam machen lassen (passiv bleiben)<\/span><br \/><span style=\"font-family:verdana;\">&#8211; Auf Anfrage <\/span><span style=\"font-family:verdana;\">inhaltlich beraten (<\/span><span style=\"font-family:verdana;\">Sinnvolle Vorschl\u00e4ge machen.)<\/span><br \/><span style=\"font-family:verdana;\">&#8211; Zum Schluss das Ergebnis inhaltlich bewerten. (Gutachten \u00fcber die Arbeitsweise und das Ergebnis schreiben)<\/span><br \/><span style=\"font-family:verdana;\">(5) Diesen Aufgaben sollte man gr\u00fcndlich nachkommen &#8230; Nicht aber mehr tun <\/span><br \/><span style=\"font-family:verdana;\">(6) Man kann &#8212; muss aber nicht &#8212; den Schreiber(innen) abbieten ihre Texte zur Probe zu lesen. <\/span><br \/><span style=\"font-family:verdana;\">&#8211; Wenn man es aber tut, sollte man sich &#8212; im Sinne der Passivit\u00e4t &#8212; nicht \u00e4rgern, wenn die m\u00fchsam erarbeiteten Vorschl\u00e4ge unbeachtet werden. (Es ist der Schreibenden Werk) <\/span><br \/><span style=\"font-family:verdana;\">(7) Beim Fachgutachten sollte man sich an die vorgegebenen Bewertungsmuster (die genauen Termini) klammer &#8212; das macht es viel einfacher.<br \/>(8) Wie auch bei allen anderen Punkten sollte man sich nicht hetzen oder stressen lassen. Es ist immer noch ein Ehrenamt.<\/p>\n<p>Ich f\u00fcr meinen Teil w\u00fcrde es wieder tun, weil ich denke, dass eine (auch nur halbwechs) wissenschaftliche Arbeit in der Schule nur gut tun kann.<br \/><\/span><\/p>\n<div class=\"blogger-post-footer\">\n<p><a href=\"http:\/\/feeds2.feedburner.com\/DieWunderbareWeltInChiffrenUndZeichen\" rel=\"alternate\"><img decoding=\"async\" src=\"http:\/\/www.feedburner.com\/fb\/images\/pub\/feed-icon16x16.png\" alt=\"\"><\/a>&nbsp;<a href=\"http:\/\/feeds2.feedburner.com\/DieWunderbareWeltInChiffrenUndZeichen\" rel=\"alternate\">Subscribe in a reader<\/a><\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Nun: Ich denke die erste Mission, mal nieder zu schreiben, wie das so l\u00e4uft mit der Betreuung einer Seminarfacharbeit, habe ich erf\u00fcllt. Hier eine kurze Zusammenfassung:(1) Die externe Betreuung einer Seminarfacharbeit, Projektarbeit oder wie immer es genannt wird ist eine Angelegenheit b\u00fcrgerschaftlichen Engagements.(2) Man m\u00f6ge diesem Job nicht hinterher rennen, er kann hin und wieder [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-27","post","type-post","status-publish","format-standard","hentry","category-gesagt"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.7 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Zusammenfassung der Arbeit als Externer Betreuer &#8902; Hannes J\u00e4hnert<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/hannes-jaehnert.de\/wordpress\/2008\/11\/12\/zusammenfassung-der-arbeit-als-externer-betreuer\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Zusammenfassung der Arbeit als Externer Betreuer &#8902; Hannes J\u00e4hnert\" \/>\n<meta property=\"og:description\" content=\"Nun: Ich denke die erste Mission, mal nieder zu schreiben, wie das so l\u00e4uft mit der Betreuung einer Seminarfacharbeit, habe ich erf\u00fcllt. Hier eine kurze Zusammenfassung:(1) Die externe Betreuung einer Seminarfacharbeit, Projektarbeit oder wie immer es genannt wird ist eine Angelegenheit b\u00fcrgerschaftlichen Engagements.(2) Man m\u00f6ge diesem Job nicht hinterher rennen, er kann hin und wieder [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/hannes-jaehnert.de\/wordpress\/2008\/11\/12\/zusammenfassung-der-arbeit-als-externer-betreuer\/\" \/>\n<meta property=\"og:site_name\" content=\"Hannes J\u00e4hnert\" \/>\n<meta property=\"article:published_time\" content=\"2008-11-12T18:23:00+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/www.feedburner.com\/fb\/images\/pub\/feed-icon16x16.png\" \/>\n<meta name=\"author\" content=\"Hannes Jahnert\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Hannes Jahnert\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"1\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/hannes-jaehnert.de\\\/wordpress\\\/2008\\\/11\\\/12\\\/zusammenfassung-der-arbeit-als-externer-betreuer\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/hannes-jaehnert.de\\\/wordpress\\\/2008\\\/11\\\/12\\\/zusammenfassung-der-arbeit-als-externer-betreuer\\\/\"},\"author\":{\"name\":\"Hannes Jahnert\",\"@id\":\"https:\\\/\\\/hannes-jaehnert.de\\\/wordpress\\\/#\\\/schema\\\/person\\\/792eb75897df270ba1e89a708848ae9c\"},\"headline\":\"Zusammenfassung der Arbeit als Externer Betreuer\",\"datePublished\":\"2008-11-12T18:23:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/hannes-jaehnert.de\\\/wordpress\\\/2008\\\/11\\\/12\\\/zusammenfassung-der-arbeit-als-externer-betreuer\\\/\"},\"wordCount\":279,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/hannes-jaehnert.de\\\/wordpress\\\/#\\\/schema\\\/person\\\/1ab60f3bc0cd8e11ede09e5dc21d43b5\"},\"image\":{\"@id\":\"https:\\\/\\\/hannes-jaehnert.de\\\/wordpress\\\/2008\\\/11\\\/12\\\/zusammenfassung-der-arbeit-als-externer-betreuer\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/www.feedburner.com\\\/fb\\\/images\\\/pub\\\/feed-icon16x16.png\",\"articleSection\":[\"Kurz Notiert\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/hannes-jaehnert.de\\\/wordpress\\\/2008\\\/11\\\/12\\\/zusammenfassung-der-arbeit-als-externer-betreuer\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/hannes-jaehnert.de\\\/wordpress\\\/2008\\\/11\\\/12\\\/zusammenfassung-der-arbeit-als-externer-betreuer\\\/\",\"url\":\"https:\\\/\\\/hannes-jaehnert.de\\\/wordpress\\\/2008\\\/11\\\/12\\\/zusammenfassung-der-arbeit-als-externer-betreuer\\\/\",\"name\":\"Zusammenfassung der Arbeit als Externer Betreuer &#8902; Hannes J\u00e4hnert\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/hannes-jaehnert.de\\\/wordpress\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/hannes-jaehnert.de\\\/wordpress\\\/2008\\\/11\\\/12\\\/zusammenfassung-der-arbeit-als-externer-betreuer\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/hannes-jaehnert.de\\\/wordpress\\\/2008\\\/11\\\/12\\\/zusammenfassung-der-arbeit-als-externer-betreuer\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/www.feedburner.com\\\/fb\\\/images\\\/pub\\\/feed-icon16x16.png\",\"datePublished\":\"2008-11-12T18:23:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/hannes-jaehnert.de\\\/wordpress\\\/2008\\\/11\\\/12\\\/zusammenfassung-der-arbeit-als-externer-betreuer\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/hannes-jaehnert.de\\\/wordpress\\\/2008\\\/11\\\/12\\\/zusammenfassung-der-arbeit-als-externer-betreuer\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/hannes-jaehnert.de\\\/wordpress\\\/2008\\\/11\\\/12\\\/zusammenfassung-der-arbeit-als-externer-betreuer\\\/#primaryimage\",\"url\":\"http:\\\/\\\/www.feedburner.com\\\/fb\\\/images\\\/pub\\\/feed-icon16x16.png\",\"contentUrl\":\"http:\\\/\\\/www.feedburner.com\\\/fb\\\/images\\\/pub\\\/feed-icon16x16.png\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/hannes-jaehnert.de\\\/wordpress\\\/2008\\\/11\\\/12\\\/zusammenfassung-der-arbeit-als-externer-betreuer\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/hannes-jaehnert.de\\\/wordpress\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Zusammenfassung der Arbeit als Externer Betreuer\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/hannes-jaehnert.de\\\/wordpress\\\/#website\",\"url\":\"https:\\\/\\\/hannes-jaehnert.de\\\/wordpress\\\/\",\"name\":\"Hannes J\u00e4hnert\",\"description\":\"Engagementblogger &amp; Freizeitforscher\",\"publisher\":{\"@id\":\"https:\\\/\\\/hannes-jaehnert.de\\\/wordpress\\\/#\\\/schema\\\/person\\\/1ab60f3bc0cd8e11ede09e5dc21d43b5\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/hannes-jaehnert.de\\\/wordpress\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/hannes-jaehnert.de\\\/wordpress\\\/#\\\/schema\\\/person\\\/1ab60f3bc0cd8e11ede09e5dc21d43b5\",\"name\":\"foulder\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/hannes-jaehnert.de\\\/wordpress\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/hannes-jaehnert_gemacht.jpg\",\"url\":\"https:\\\/\\\/hannes-jaehnert.de\\\/wordpress\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/hannes-jaehnert_gemacht.jpg\",\"contentUrl\":\"https:\\\/\\\/hannes-jaehnert.de\\\/wordpress\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/hannes-jaehnert_gemacht.jpg\",\"width\":2000,\"height\":2000,\"caption\":\"foulder\"},\"logo\":{\"@id\":\"https:\\\/\\\/hannes-jaehnert.de\\\/wordpress\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/hannes-jaehnert_gemacht.jpg\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/hannes-jaehnert.de\\\/wordpress\\\/#\\\/schema\\\/person\\\/792eb75897df270ba1e89a708848ae9c\",\"name\":\"Hannes Jahnert\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/?s=96&d=mm&r=g\",\"caption\":\"Hannes Jahnert\"},\"url\":\"https:\\\/\\\/hannes-jaehnert.de\\\/wordpress\\\/author\\\/hannes-jahnert\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Zusammenfassung der Arbeit als Externer Betreuer &#8902; Hannes J\u00e4hnert","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/hannes-jaehnert.de\/wordpress\/2008\/11\/12\/zusammenfassung-der-arbeit-als-externer-betreuer\/","og_locale":"de_DE","og_type":"article","og_title":"Zusammenfassung der Arbeit als Externer Betreuer &#8902; Hannes J\u00e4hnert","og_description":"Nun: Ich denke die erste Mission, mal nieder zu schreiben, wie das so l\u00e4uft mit der Betreuung einer Seminarfacharbeit, habe ich erf\u00fcllt. Hier eine kurze Zusammenfassung:(1) Die externe Betreuung einer Seminarfacharbeit, Projektarbeit oder wie immer es genannt wird ist eine Angelegenheit b\u00fcrgerschaftlichen Engagements.(2) Man m\u00f6ge diesem Job nicht hinterher rennen, er kann hin und wieder [&hellip;]","og_url":"https:\/\/hannes-jaehnert.de\/wordpress\/2008\/11\/12\/zusammenfassung-der-arbeit-als-externer-betreuer\/","og_site_name":"Hannes J\u00e4hnert","article_published_time":"2008-11-12T18:23:00+00:00","og_image":[{"url":"http:\/\/www.feedburner.com\/fb\/images\/pub\/feed-icon16x16.png","type":"","width":"","height":""}],"author":"Hannes Jahnert","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Hannes Jahnert","Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/hannes-jaehnert.de\/wordpress\/2008\/11\/12\/zusammenfassung-der-arbeit-als-externer-betreuer\/#article","isPartOf":{"@id":"https:\/\/hannes-jaehnert.de\/wordpress\/2008\/11\/12\/zusammenfassung-der-arbeit-als-externer-betreuer\/"},"author":{"name":"Hannes Jahnert","@id":"https:\/\/hannes-jaehnert.de\/wordpress\/#\/schema\/person\/792eb75897df270ba1e89a708848ae9c"},"headline":"Zusammenfassung der Arbeit als Externer Betreuer","datePublished":"2008-11-12T18:23:00+00:00","mainEntityOfPage":{"@id":"https:\/\/hannes-jaehnert.de\/wordpress\/2008\/11\/12\/zusammenfassung-der-arbeit-als-externer-betreuer\/"},"wordCount":279,"commentCount":0,"publisher":{"@id":"https:\/\/hannes-jaehnert.de\/wordpress\/#\/schema\/person\/1ab60f3bc0cd8e11ede09e5dc21d43b5"},"image":{"@id":"https:\/\/hannes-jaehnert.de\/wordpress\/2008\/11\/12\/zusammenfassung-der-arbeit-als-externer-betreuer\/#primaryimage"},"thumbnailUrl":"http:\/\/www.feedburner.com\/fb\/images\/pub\/feed-icon16x16.png","articleSection":["Kurz Notiert"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/hannes-jaehnert.de\/wordpress\/2008\/11\/12\/zusammenfassung-der-arbeit-als-externer-betreuer\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/hannes-jaehnert.de\/wordpress\/2008\/11\/12\/zusammenfassung-der-arbeit-als-externer-betreuer\/","url":"https:\/\/hannes-jaehnert.de\/wordpress\/2008\/11\/12\/zusammenfassung-der-arbeit-als-externer-betreuer\/","name":"Zusammenfassung der Arbeit als Externer Betreuer &#8902; Hannes J\u00e4hnert","isPartOf":{"@id":"https:\/\/hannes-jaehnert.de\/wordpress\/#website"},"primaryImageOfPage":{"@id":"https:\/\/hannes-jaehnert.de\/wordpress\/2008\/11\/12\/zusammenfassung-der-arbeit-als-externer-betreuer\/#primaryimage"},"image":{"@id":"https:\/\/hannes-jaehnert.de\/wordpress\/2008\/11\/12\/zusammenfassung-der-arbeit-als-externer-betreuer\/#primaryimage"},"thumbnailUrl":"http:\/\/www.feedburner.com\/fb\/images\/pub\/feed-icon16x16.png","datePublished":"2008-11-12T18:23:00+00:00","breadcrumb":{"@id":"https:\/\/hannes-jaehnert.de\/wordpress\/2008\/11\/12\/zusammenfassung-der-arbeit-als-externer-betreuer\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/hannes-jaehnert.de\/wordpress\/2008\/11\/12\/zusammenfassung-der-arbeit-als-externer-betreuer\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/hannes-jaehnert.de\/wordpress\/2008\/11\/12\/zusammenfassung-der-arbeit-als-externer-betreuer\/#primaryimage","url":"http:\/\/www.feedburner.com\/fb\/images\/pub\/feed-icon16x16.png","contentUrl":"http:\/\/www.feedburner.com\/fb\/images\/pub\/feed-icon16x16.png"},{"@type":"BreadcrumbList","@id":"https:\/\/hannes-jaehnert.de\/wordpress\/2008\/11\/12\/zusammenfassung-der-arbeit-als-externer-betreuer\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/hannes-jaehnert.de\/wordpress\/"},{"@type":"ListItem","position":2,"name":"Zusammenfassung der Arbeit als Externer Betreuer"}]},{"@type":"WebSite","@id":"https:\/\/hannes-jaehnert.de\/wordpress\/#website","url":"https:\/\/hannes-jaehnert.de\/wordpress\/","name":"Hannes J\u00e4hnert","description":"Engagementblogger &amp; Freizeitforscher","publisher":{"@id":"https:\/\/hannes-jaehnert.de\/wordpress\/#\/schema\/person\/1ab60f3bc0cd8e11ede09e5dc21d43b5"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/hannes-jaehnert.de\/wordpress\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":["Person","Organization"],"@id":"https:\/\/hannes-jaehnert.de\/wordpress\/#\/schema\/person\/1ab60f3bc0cd8e11ede09e5dc21d43b5","name":"foulder","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/hannes-jaehnert.de\/wordpress\/wp-content\/uploads\/2021\/02\/hannes-jaehnert_gemacht.jpg","url":"https:\/\/hannes-jaehnert.de\/wordpress\/wp-content\/uploads\/2021\/02\/hannes-jaehnert_gemacht.jpg","contentUrl":"https:\/\/hannes-jaehnert.de\/wordpress\/wp-content\/uploads\/2021\/02\/hannes-jaehnert_gemacht.jpg","width":2000,"height":2000,"caption":"foulder"},"logo":{"@id":"https:\/\/hannes-jaehnert.de\/wordpress\/wp-content\/uploads\/2021\/02\/hannes-jaehnert_gemacht.jpg"}},{"@type":"Person","@id":"https:\/\/hannes-jaehnert.de\/wordpress\/#\/schema\/person\/792eb75897df270ba1e89a708848ae9c","name":"Hannes Jahnert","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/?s=96&d=mm&r=g","caption":"Hannes Jahnert"},"url":"https:\/\/hannes-jaehnert.de\/wordpress\/author\/hannes-jahnert\/"}]}},"views":777,"_links":{"self":[{"href":"https:\/\/hannes-jaehnert.de\/wordpress\/wp-json\/wp\/v2\/posts\/27","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hannes-jaehnert.de\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/hannes-jaehnert.de\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/hannes-jaehnert.de\/wordpress\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/hannes-jaehnert.de\/wordpress\/wp-json\/wp\/v2\/comments?post=27"}],"version-history":[{"count":0,"href":"https:\/\/hannes-jaehnert.de\/wordpress\/wp-json\/wp\/v2\/posts\/27\/revisions"}],"wp:attachment":[{"href":"https:\/\/hannes-jaehnert.de\/wordpress\/wp-json\/wp\/v2\/media?parent=27"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/hannes-jaehnert.de\/wordpress\/wp-json\/wp\/v2\/categories?post=27"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/hannes-jaehnert.de\/wordpress\/wp-json\/wp\/v2\/tags?post=27"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}